


{"id":5784,"date":"2020-01-27T19:16:41","date_gmt":"2020-01-27T18:16:41","guid":{"rendered":"https:\/\/www.rome-roma.net\/site\/musees-du-capitole\/"},"modified":"2026-04-04T17:30:23","modified_gmt":"2026-04-04T15:30:23","slug":"musei-capitolini","status":"publish","type":"site","link":"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/","title":{"rendered":"Musei Capitolini"},"content":{"rendered":"<p align=\"left\"><a href=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/musei-capitolini-roma_0480.jpg\"><img loading=\"lazy\" class=\"alignright wp-image-33164 size-medium\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/musei-capitolini-roma_0480-300x200.jpg\" alt=\"Rilievo ai Musei del Campidoglio\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/musei-capitolini-roma_0480-300x200.jpg 300w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/musei-capitolini-roma_0480-1024x683.jpg 1024w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/musei-capitolini-roma_0480-768x512.jpg 768w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/musei-capitolini-roma_0480.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>I <strong>Musei Capitolini<\/strong> si trovano nei palazzi di <a href=\"https:\/\/www.rome-roma.net\/it\/piazza-del-campidoglio\/\">Piazza del Campidoglio<\/a>, ovvero il <strong>Palazzo Nuovo<\/strong> e il <strong>Palazzo dei Conservatori<\/strong>. \u00c8 il primo museo di Roma da visitare per chiunque sia interessato all&#8217;antichit\u00e0 romana. Le sue vaste collezioni, in gran parte dedicate all&#8217;antichit\u00e0, ospitano numerosi capolavori, tra cui statue e reperti archeologici, nonch\u00e9 una pinacoteca con tele di grande valore.<\/p>\n<h2 align=\"left\">Presentazione storica<\/h2>\n<p>Le origini della collezione del museo risalgono al 1471, quando Papa <strong>Sisto IV<\/strong> don\u00f2 ai romani delle statue di bronzo. Successivamente, le collezioni furono notevolmente arricchite grazie agli scavi archeologici condotti a Roma e in Vaticano, nonch\u00e9 ad acquisti come l&#8217;acquisizione della collezione Albani. Nel 1734, all&#8217;interno del Palazzo Nuovo, Papa <strong>Clemente XII<\/strong> fond\u00f2 il primo museo pubblico del mondo.<\/p>\n<p>Nel 1749, Papa Benedetto XIV inaugur\u00f2 la pinacoteca del Palazzo dei Conservatori, che ospita dipinti di maestri prestigiosi come Caravaggio, Veronese, Tintoretto, Tiziano e Van Dyck. \u00c8 alla fine del XIX secolo che le collezioni archeologiche si svilupparono veramente, soprattutto grazie agli scavi effettuati durante la costruzione dei nuovi quartieri della citt\u00e0 al di fuori delle mura aureliane.<\/p>\n<h2>Descrizione dei musei<\/h2>\n<div id=\"attachment_33327\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/mosaico-con-mascherine-teatrali-musei-capitolini-roma_6621.jpg\"><img aria-describedby=\"caption-attachment-33327\" loading=\"lazy\" class=\"wp-image-33327 size-medium\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/mosaico-con-mascherine-teatrali-musei-capitolini-roma_6621-300x200.jpg\" alt=\"Mosaici con maschere teatrali, musei capitolini\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/mosaico-con-mascherine-teatrali-musei-capitolini-roma_6621-300x200.jpg 300w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/mosaico-con-mascherine-teatrali-musei-capitolini-roma_6621-1024x683.jpg 1024w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/mosaico-con-mascherine-teatrali-musei-capitolini-roma_6621-768x512.jpg 768w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/mosaico-con-mascherine-teatrali-musei-capitolini-roma_6621.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-33327\" class=\"wp-caption-text\">Mosaici con maschere teatrali<\/p><\/div>\n<p>I due palazzi che ospitano i Musei Capitolini si trovano in <a href=\"https:\/\/www.rome-roma.net\/it\/piazza-del-campidoglio\/\">Piazza del Campidoglio<\/a>, ai lati del <strong>Palazzo Senatorio<\/strong>. Sono collegati da una galleria sotterranea che passa sotto quest&#8217;ultimo e ospita la <strong>Galleria Lapidaria<\/strong>. Questa galleria attraversa l&#8217;antico <strong>Tabularium<\/strong> e offre splendide viste sul Foro, visibili attraverso le sue imponenti arcate.<\/p>\n<h3>Palazzo Nuovo<\/h3>\n<p>Il <strong>Palazzo Nuovo<\/strong> \u00e8 cambiato poco dal XVIII secolo, conservando una ricca collezione di sculture antiche, provenienti principalmente dalle grandi famiglie romane. Tra i pezzi principali ci sono busti di filosofi e imperatori, testimoniando l&#8217;importanza del pensiero e del potere nell&#8217;arte romana, con opere famose come quelle di Seneca e Marco Aurelio.<\/p>\n<p>La <strong>Sala dei filosofi<\/strong> presenta busti in marmo di figure emblematiche della filosofia greca, come Socrate, Platone e Aristotele, che influenzarono il pensiero intellettuale e culturale della Roma antica.<\/p>\n<div id=\"attachment_32586\" style=\"width: 210px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/trajan-bustes-empereurs-romains-musees-capitole_6548.jpg\"><img aria-describedby=\"caption-attachment-32586\" loading=\"lazy\" class=\"wp-image-32586 size-medium\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/trajan-bustes-empereurs-romains-musees-capitole_6548-200x300.jpg\" alt=\"Busto ritratto di Traiano, imperatore romano\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/trajan-bustes-empereurs-romains-musees-capitole_6548-200x300.jpg 200w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/trajan-bustes-empereurs-romains-musees-capitole_6548-683x1024.jpg 683w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/trajan-bustes-empereurs-romains-musees-capitole_6548-768x1152.jpg 768w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/trajan-bustes-empereurs-romains-musees-capitole_6548.jpg 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><p id=\"caption-attachment-32586\" class=\"wp-caption-text\">Busto di Traiano<\/p><\/div>\n<p>La <strong>Sala degli imperatori<\/strong>, situata al primo piano, ospita una vasta collezione di busti e statue degli imperatori romani, come quelli di Tiberio, Claudio e Augusto, che illustrano l&#8217;ideologia imperiale dell&#8217;epoca.<br>Tra le altre opere notevoli, si trova la statua del <strong><em>Galata morente<\/em><\/strong>, la <strong><em>Venere Capitolina<\/em><\/strong>, nonch\u00e9 la grande statua acquatica del <strong><em>Marforio<\/em><\/strong>, una delle celebri &#8220;statue parlanti&#8221; di Roma, situata nel cortile del museo.<\/p>\n<h3>Palazzo dei Conservatori<\/h3>\n<p>Il <strong>Palazzo dei Conservatori<\/strong> conserva, a sua volta, le stanze degli appartamenti originali, decorate con affreschi che rappresentano episodi storici di Roma. Ospita anche pezzi importanti della scultura antica, come i bronzi capitolini, tra cui la famosa <em>Lupa Capitolina<\/em>, lo <em>Spinario<\/em> e il <em>Bruto Capitolino<\/em>.<\/p>\n<p>Al <strong>primo piano<\/strong>, una grande sala vetrata ospita l&#8217;originale della <strong>statua equestre in bronzo di Marco Aurelio<\/strong>, una copia della quale si trova al centro di <a href=\"https:\/\/www.rome-roma.net\/it\/piazza-del-campidoglio\/\">Piazza del Campidoglio<\/a>.<\/p>\n<div id=\"attachment_33150\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/statue-equestre-de-marc-aurele-original-musees-du-capitole-rome_0499.jpg\"><img aria-describedby=\"caption-attachment-33150\" loading=\"lazy\" class=\"wp-image-33150 size-medium\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/statue-equestre-de-marc-aurele-original-musees-du-capitole-rome_0499-300x200.jpg\" alt=\"Statua equestre di Marco Aurelio, Musei Capitolici\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/statue-equestre-de-marc-aurele-original-musees-du-capitole-rome_0499-300x200.jpg 300w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/statue-equestre-de-marc-aurele-original-musees-du-capitole-rome_0499-1024x683.jpg 1024w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/statue-equestre-de-marc-aurele-original-musees-du-capitole-rome_0499-768x512.jpg 768w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/statue-equestre-de-marc-aurele-original-musees-du-capitole-rome_0499.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-33150\" class=\"wp-caption-text\">Statua equestre di Marco Aurelio<\/p><\/div>\n<p>Si possono anche scoprire i resti del <a href=\"https:\/\/www.rome-roma.net\/it\/tempio-di-giove-capitolino\/\">Tempio di Giove Capitolino<\/a> e una sezione dedicata alla storia del Campidoglio dalle sue origini.<\/p>\n<p>Le stanze adiacenti espongono opere provenienti dagli <strong>Horti dell&#8217;Esquilino<\/strong>, cos\u00ec come altre collezioni preziose.<\/p>\n<p>Al secondo piano, la <strong>Pinacoteca Capitolina<\/strong> ospita tele che vanno dalla fine del Medioevo al XVIII secolo. Tra i capolavori ci sono dipinti del <strong>Caravaggio<\/strong> (tra cui La <em>Cartomante<\/em> e <em>San Giovanni Battista<\/em>), un grande quadro del <strong>Guercino<\/strong> raffigurante <em>Il funerale di Santa Petronilla<\/em>, cos\u00ec come opere di Guido Reni, Pietro da Cortona, Veronese, Tintoretto e Tiziano.<\/p>\n<h3>Galleria del Tabularium<\/h3>\n<p>La galleria che collega i due palazzi attraversa il <strong>Tabularium<\/strong>, un edificio romano emblematico che serviva da archivio pubblico per la citt\u00e0 di Roma. Oggi integrato nel percorso museale, questa struttura offre ai visitatori una vista spettacolare sul Foro Romano.<\/p>\n<div id=\"attachment_33247\" style=\"width: 210px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/tabularium-musei-capitolini-roma_0531.jpg\"><img aria-describedby=\"caption-attachment-33247\" loading=\"lazy\" class=\"wp-image-33247 size-medium\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/tabularium-musei-capitolini-roma_0531-200x300.jpg\" alt=\"Tabularium, palazzo dei conservatori, Roma\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/tabularium-musei-capitolini-roma_0531-200x300.jpg 200w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/tabularium-musei-capitolini-roma_0531-683x1024.jpg 683w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/tabularium-musei-capitolini-roma_0531-768x1152.jpg 768w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/tabularium-musei-capitolini-roma_0531.jpg 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><p id=\"caption-attachment-33247\" class=\"wp-caption-text\">Tabularium<\/p><\/div>\n<p>Ospita una collezione costituita in parte dai resti ritrovati durante gli scavi del Foro Romano e dei suoi dintorni, come iscrizioni e rilievi lapidari (su tavolette di bronzo e stele), frammenti scolpiti provenienti da edifici pubblici, monumenti ed elementi architettonici (basi di statue, colonne, pezzi di templi antichi), oggetti personali.<\/p>\n<h3>Palazzo Caffarelli-Clementino<\/h3>\n<p>Il <strong>Palazzo Caffarelli-Clementino<\/strong> ospita la <strong>collezione di medaglie del Campidoglio<\/strong>, che comprende monete, pietre preziose e gioielli di grande valore. Accoglie anche mostre temporanee.<\/p>\n<p style=\"text-align: right;\">\u2192 Vedi sul sito ufficiale: <a href=\"https:\/\/www.museicapitolini.org\/it\/collezioni\/percorsi_per_sale\" target=\"_blank\" rel=\"noopener\">percorso completo delle sale dei Musei Capitolini<\/a><\/p>\n<p><\/p>\n\n\n<h2>Opere dei Musei Capitolini<\/h2>\n\n\n\n<ul class=\"lcp_catlist\" id=\"lcp_instance_0\"><li class=\"current\"><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/\">Musei Capitolini<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/\" title=\"Musei Capitolini\"><img width=\"50\" height=\"50\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/musei-capitolini-roma_0480-150x150.jpg\" class=\"classthumblist wp-post-image\" alt=\"Musei Capitolini\" loading=\"lazy\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/musei-capitolini-roma_0480-150x150.jpg 150w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/musei-capitolini-roma_0480-50x50.jpg 50w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/musei-capitolini-roma_0480-80x80.jpg 80w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/musei-capitolini-roma_0480-75x75.jpg 75w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><div class=\"lcp_excerpt\">I Musei Capitolini si trovano nei palazzi di Piazza del Campidoglio, ovvero il Palazzo Nuovo e il Palazzo dei Conservatori. \u00c8 il ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/busti-degli-imperatori\/\">Busti degli imperatori ed altri<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/busti-degli-imperatori\/\" title=\"Busti degli imperatori ed altri\"><img width=\"50\" height=\"50\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/caracalla_musee_capitole_empereurs_65811-150x150.jpg\" class=\"classthumblist wp-post-image\" alt=\"Busti degli imperatori ed altri\" loading=\"lazy\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/caracalla_musee_capitole_empereurs_65811-150x150.jpg 150w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/caracalla_musee_capitole_empereurs_65811-50x50.jpg 50w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/caracalla_musee_capitole_empereurs_65811-80x80.jpg 80w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/caracalla_musee_capitole_empereurs_65811-75x75.jpg 75w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><div class=\"lcp_excerpt\">Ai Musei Capitolini di Roma, diverse sale del Palazzo Nuovo sono dedicate all&#8217;esposizione di busti romani, in particolare quelli degli imperatori, filosofi, ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/pinacoteca-dei-musei-capitolini\/\">Pinacoteca dei Musei Capitolini<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/pinacoteca-dei-musei-capitolini\/\" title=\"Pinacoteca dei Musei Capitolini\"><img width=\"50\" height=\"50\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musei_capitolini_65071-150x150.jpg\" class=\"classthumblist wp-post-image\" alt=\"Pinacoteca dei Musei Capitolini\" loading=\"lazy\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musei_capitolini_65071-150x150.jpg 150w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musei_capitolini_65071-50x50.jpg 50w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musei_capitolini_65071-80x80.jpg 80w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musei_capitolini_65071-75x75.jpg 75w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><div class=\"lcp_excerpt\">La Pinacoteca Capitolina, situata nel Palazzo dei Conservatori dei Musei Capitolini a Roma, \u00e8 la pi\u00f9 antica collezione pubblica di dipinti al ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/sculture-nei-musei-capitolini\/\">Sculture nei Musei Capitolini<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/sculture-nei-musei-capitolini\/\" title=\"Sculture nei Musei Capitolini\"><img width=\"50\" height=\"50\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musees_du_capitole_64681-150x150.jpg\" class=\"classthumblist wp-post-image\" alt=\"Sculture nei Musei Capitolini\" loading=\"lazy\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musees_du_capitole_64681-150x150.jpg 150w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musees_du_capitole_64681-50x50.jpg 50w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musees_du_capitole_64681-80x80.jpg 80w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musees_du_capitole_64681-75x75.jpg 75w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><div class=\"lcp_excerpt\">Ai Musei Capitolini di Roma, numerose statue antiche&nbsp; e alcune pi\u00f9 recenti illustrano la ricchezza artistica e simbolica della Roma imperiale e ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/sale-del-palazzo-dei-conservatori\/\">Sale del Palazzo dei Conservatori e Tabularium<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/sale-del-palazzo-dei-conservatori\/\" title=\"Sale del Palazzo dei Conservatori e Tabularium\"><img width=\"50\" height=\"50\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musees_du_capitole_64601-150x150.jpg\" class=\"classthumblist wp-post-image\" alt=\"Sale del Palazzo dei Conservatori e Tabularium\" loading=\"lazy\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musees_du_capitole_64601-150x150.jpg 150w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musees_du_capitole_64601-50x50.jpg 50w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musees_du_capitole_64601-80x80.jpg 80w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/musees_du_capitole_64601-75x75.jpg 75w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><div class=\"lcp_excerpt\">Il Palazzo dei Conservatori, situato in Piazza del Campidoglio, ospita gran parte delle collezioni dei musei capitolini, insieme al Palazzo Nuovo di ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/tabularium-antichita-romane\/\">Antichit\u00e0 romane: sculture, museo epigrafico, sarcofagi<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/tabularium-antichita-romane\/\" title=\"Antichit\u00e0 romane: sculture, museo epigrafico, sarcofagi\"><img width=\"50\" height=\"50\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/base_museocampidoglio_05271-150x150.jpg\" class=\"classthumblist wp-post-image\" alt=\"Antichit\u00e0 romane: sculture, museo epigrafico, sarcofagi\" loading=\"lazy\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/base_museocampidoglio_05271-150x150.jpg 150w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/base_museocampidoglio_05271-50x50.jpg 50w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/base_museocampidoglio_05271-80x80.jpg 80w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/base_museocampidoglio_05271-75x75.jpg 75w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><div class=\"lcp_excerpt\">Ai Musei Capitolini a Roma, numerosi oggetti antichi completano le celebri statue e i busti, dal Palazzo Nuovo al Palazzo dei Conservatori. ...<\/div><\/li><\/ul>\n\n\n\n<h2>Visita ed informazioni<\/h2>\n\n\n<p style=\"vertical-align: middle; display: inline-block;\"><table style=\"margin-bottom: 0rem;\"><tbody><tr style=\"background-color:#fcfaf7; \" \r\n    onmouseover=\"this.style.backgroundColor='#f7dbb8';\" \r\n    onmouseout=\"this.style.backgroundColor='#fcfaf7';\"><td style=\"vertical-align: middle; text-align: right;\"><a href=\"https:\/\/www.getyourguide.it\/musees-du-capitole-l3299\/?partner_id=DLYVAO3&#038;utm_medium=online_publisher&#038;placement=content-top\" target=\"_blank\" rel=\"nofollow noopener\">Biglietti per visitare i Musei Capitolini<\/a><\/td><td style=\"width:70px;\"><a href=\"https:\/\/www.getyourguide.it\/musees-du-capitole-l3299\/?partner_id=DLYVAO3&#038;utm_medium=online_publisher&#038;placement=content-top\" target=\"_blank\" rel=\"nofollow noopener\"><img style=\"display:inline;vertical-align:middle;padding:5px;\" src=\"https:\/\/www.rome-roma.net\/images\/icones\/icone-tickets2.png\" alt=\"icona biglietti visita\" title=\"Biglietti per visitare i Musei Capitolini\" width=\"65\" align=\"center\"><\/a><\/td><\/tr><tr style=\"background-color:#ffffff; \" \r\n    onmouseover=\"this.style.backgroundColor='#f7dbb8';\" \r\n    onmouseout=\"this.style.backgroundColor='#ffffff';\"><td style=\"vertical-align: middle; text-align: right;\"><a href=\"https:\/\/www.booking.com\/searchresults.it.html?aid=308344;label=headerlandmark;landmark=2128;group_adults=2;no_rooms=1;group_children=0;nflt=review_score=80%3Bdistance=1000\" target=\"_blank\" rel=\"nofollow noopener\">Alberghi, camere e appartamenti vicino al monumento<\/a><\/td><td style=\"width:70px;\"><a href=\"https:\/\/www.booking.com\/searchresults.it.html?aid=308344;label=headerlandmark;landmark=2128;group_adults=2;no_rooms=1;group_children=0;nflt=review_score=80%3Bdistance=1000\" target=\"_blank\" rel=\"nofollow noopener\"><img style=\"display:inline;vertical-align:middle;padding:5px;\" src=\"https:\/\/www.rome-roma.net\/images\/icones\/icone-hotel22.png\" alt=\"icona alberghi\" title=\"Alberghi, camere e appartamenti vicino al monumento\" width=\"65\" align=\"center\"><\/a><\/td><\/tr><\/tbody><\/table>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr style=\"background-color: #fae8c3;\">\n<td style=\"width: 100%;\">\n<p><span style=\"font-size: 10pt;\"><strong>Orari e visite<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 10pt;\">Aperto tutti i giorni dalle 9.30 alle 19.30 (ingressi fino alle 18.30)<\/span><br \/><span style=\"font-size: 10pt;\">Chiuso il 1\u00ba maggio e 25 dicembre<\/span><br \/><span style=\"font-size: 10pt;\">24 e 31 dicembre: dalle 9.30 alle 14.00 (entrate fino alle 13.00)<br \/>1o gennaio 2026: dalle 11 alle 20<br \/><\/span><\/li>\n<li><span style=\"font-size: 10pt;\">Tariffe biglietto in assenza di esposizione: intero \u20ac 15 \/ ridotto \u20ac 9,50<\/span><br \/><span style=\"font-size: 10pt;\">Tariffa con le mostra in corso possono essere maggiorati<\/span><br \/><span style=\"font-size: 10pt;\">Audioguida \u20ac 4, Videoguida \u20ac 6<\/span><\/li>\n<li><span style=\"font-size: 10pt;\">Capitolini Card (Musei Capitolini + Centrale Montemartini) e mostre, valida 7 giorni:<\/span><br \/><span style=\"font-size: 10pt;\">Tariffa se non c&#8217;\u00e8 esposizione in corso: intero \u20ac 15,50 \/ ridotto \u20ac 11,50<\/span><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"background-color: #f7ece1;\">\n<td style=\"width: 100%;\">\n<p><span style=\"font-size: 10pt;\"><strong>Collegamenti<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 10pt;\">Sito ufficiale : <a href=\"https:\/\/www.museicapitolini.org\/\" target=\"_blank\" rel=\"noopener\">www.museicapitolini.org<\/a><\/span><\/li>\n<li><span style=\"font-size: 10pt;\">Sito del comune di Roma : <a href=\"https:\/\/060608.comune.roma.it\/cultura\/musei\/musei-capitolini-3103\" target=\"_blank\" rel=\"noopener\">Musei Capitolini su 060608<\/a><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><a href=\"https:\/\/it.wikipedia.org\/wiki\/Musei_Capitolini\" target=\"_blank\" rel=\"noopener noreferrer\">Pagina Wikipedia<\/a><\/span><\/li>\n<li><a href=\"https:\/\/tourvirtuale.museicapitolini.org\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 10pt;\">Visita virtuale<\/span><\/a><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 100%;\">\n<p><span style=\"font-size: 10pt;\"><div data-gyg-href=\"https:\/\/widget.getyourguide.com\/default\/activities.frame\" data-gyg-location-id=\"3299\" data-gyg-locale-code=\"it-IT\" data-gyg-widget=\"activities\" data-gyg-number-of-items=\"2\" data-gyg-excluded-tour-ids=\"28847,382766\" data-gyg-partner-id=\"DLYVAO3\"><\/div><\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\n<h2>Cartina ed indirizzo<\/h2>\r\n\t\t<b>Indirizzo : <\/b>Piazza del Campidoglio, 1, 00186 Roma RM, Italie<div id=\"travelersmap-container-6a04fc82231e0\" class=\"travelersmap-container\" style=\"z-index: 1; min-height: 10px; min-width:10px; height:400px;width:100%; max-width:; max-height:; position:relative;\"><div style=\"position:absolute; z-index:-1;top: 50%;text-align: center;display: block;left: 50%;transform: translate(-50%,-50%);\">Travelers' Map is loading... <br> If you see this after your page is loaded completely, leafletJS files are missing.<\/div><\/div><i>Clicca sulla freccia per localizzarti sulla mappa<\/i>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Musei Capitolini si trovano nei palazzi di Piazza del Campidoglio, ovvero il Palazzo Nuovo e il Palazzo dei Conservatori. \u00c8 il primo museo di Roma da visitare per chiunque sia interessato all&#8217;antichit\u00e0 romana. Le sue vaste collezioni, in gran parte dedicate all&#8217;antichit\u00e0, ospitano numerosi capolavori, tra cui statue e reperti archeologici, nonch\u00e9 una pinacoteca [&hellip;]<\/p>\n","protected":false},"featured_media":33389,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"kt_blocks_editor_width":"","_links_to":"","_links_to_target":""},"genre":[275,277],"interet":[289],"quartier":[314],"categorie_site":[362,367,391,407],"quartier_historique":[442],"etiquettes_site":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Musei Capitolini &ndash; Rome-Roma<\/title>\n<meta name=\"description\" content=\"Scoperta dei Musei Capitolini a Roma, visita, itinerario, informazioni e orari. Descrizione delle collezioni, opere e sculture antiche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Musei Capitolini &ndash; Rome-Roma\" \/>\n<meta property=\"og:description\" content=\"Scoperta dei Musei Capitolini a Roma, visita, itinerario, informazioni e orari. Descrizione delle collezioni, opere e sculture antiche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/\" \/>\n<meta property=\"og:site_name\" content=\"Rome-Roma\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-04T15:30:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/musei-capitolini-roma_0480.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/#organization\",\"name\":\"Rome-Roma\",\"url\":\"https:\/\/www.rome-roma.net\/it\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg\",\"contentUrl\":\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg\",\"width\":420,\"height\":420,\"caption\":\"Rome-Roma\"},\"image\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/#website\",\"url\":\"https:\/\/www.rome-roma.net\/it\/\",\"name\":\"Rome-Roma\",\"description\":\"Cultura & Viaggio\",\"publisher\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rome-roma.net\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/musei-capitolini-roma_0480.jpg\",\"contentUrl\":\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/musei-capitolini-roma_0480.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Mus\\u00e9es du Capitole \\u00e0 Rome\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/#webpage\",\"url\":\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/\",\"name\":\"Musei Capitolini &ndash; Rome-Roma\",\"isPartOf\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/#primaryimage\"},\"datePublished\":\"2020-01-27T18:16:41+00:00\",\"dateModified\":\"2026-04-04T15:30:23+00:00\",\"description\":\"Scoperta dei Musei Capitolini a Roma, visita, itinerario, informazioni e orari. Descrizione delle collezioni, opere e sculture antiche.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.rome-roma.net\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Musei Capitolini\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Musei Capitolini &ndash; Rome-Roma","description":"Scoperta dei Musei Capitolini a Roma, visita, itinerario, informazioni e orari. Descrizione delle collezioni, opere e sculture antiche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/","og_locale":"it_IT","og_type":"article","og_title":"Musei Capitolini &ndash; Rome-Roma","og_description":"Scoperta dei Musei Capitolini a Roma, visita, itinerario, informazioni e orari. Descrizione delle collezioni, opere e sculture antiche.","og_url":"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/","og_site_name":"Rome-Roma","article_modified_time":"2026-04-04T15:30:23+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/musei-capitolini-roma_0480.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.rome-roma.net\/it\/#organization","name":"Rome-Roma","url":"https:\/\/www.rome-roma.net\/it\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.rome-roma.net\/it\/#logo","inLanguage":"it-IT","url":"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg","contentUrl":"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg","width":420,"height":420,"caption":"Rome-Roma"},"image":{"@id":"https:\/\/www.rome-roma.net\/it\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.rome-roma.net\/it\/#website","url":"https:\/\/www.rome-roma.net\/it\/","name":"Rome-Roma","description":"Cultura & Viaggio","publisher":{"@id":"https:\/\/www.rome-roma.net\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rome-roma.net\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/musei-capitolini-roma_0480.jpg","contentUrl":"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/musei-capitolini-roma_0480.jpg","width":1200,"height":800,"caption":"Mus\u00e9es du Capitole \u00e0 Rome"},{"@type":"WebPage","@id":"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/#webpage","url":"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/","name":"Musei Capitolini &ndash; Rome-Roma","isPartOf":{"@id":"https:\/\/www.rome-roma.net\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/#primaryimage"},"datePublished":"2020-01-27T18:16:41+00:00","dateModified":"2026-04-04T15:30:23+00:00","description":"Scoperta dei Musei Capitolini a Roma, visita, itinerario, informazioni e orari. Descrizione delle collezioni, opere e sculture antiche.","breadcrumb":{"@id":"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rome-roma.net\/it\/musei-capitolini\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rome-roma.net\/it\/musei-capitolini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.rome-roma.net\/it\/"},{"@type":"ListItem","position":2,"name":"Musei Capitolini"}]}]}},"acf_fields":{"nom_monument":"Musei Capitolini","wikidata":"Q333906","sameas":"https:\/\/it.wikipedia.org\/wiki\/Musei_Capitolini, https:\/\/www.museicapitolini.org\/"},"_links":{"self":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/site\/5784"}],"collection":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/site"}],"about":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/types\/site"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/comments?post=5784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/media\/33389"}],"wp:attachment":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/media?parent=5784"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/genre?post=5784"},{"taxonomy":"interet","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/interet?post=5784"},{"taxonomy":"quartier","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/quartier?post=5784"},{"taxonomy":"categorie_site","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/categorie_site?post=5784"},{"taxonomy":"quartier_historique","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/quartier_historique?post=5784"},{"taxonomy":"etiquettes_site","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/etiquettes_site?post=5784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}