


{"id":7549,"date":"2020-01-20T16:46:23","date_gmt":"2020-01-20T15:46:23","guid":{"rendered":"https:\/\/www.rome-roma.net\/site\/santo-stefano-rotondo\/"},"modified":"2024-12-13T21:49:06","modified_gmt":"2024-12-13T20:49:06","slug":"chiesa-santo-stefano-rotondo","status":"publish","type":"site","link":"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/","title":{"rendered":"Chiesa Santo Stefano Rotondo"},"content":{"rendered":"<div style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0898.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0898.jpg\" alt=\"rome - santo stefano rotondo\" width=\"300\" height=\"200\" align=\"right\" border=\"0\" hspace=\"10\" vspace=\"10\" \/><\/a><p class=\"wp-caption-text\">Colonnato circolare in Santa Stefano Rotondo<\/p><\/div>\n<p>Sul colle Celio, la <strong>chiesa di Santo Stefano Rotondo<\/strong>, costruita nel V secolo, \u00e8 una delle chiese circolari pi\u00f9 antiche d&#8217;Italia, la prima in Roma.<br \/>Fu consacrata a San Stefano alla fine del V secolo.<\/p>\n<p>Il piano originale comprendeva due colonnati concentrici, delimitando due ambulacri concentrici, con un diametro totale di 65 metri, che tagliavano le quattro braccia di una croce greca.<\/p>\n<p>Papa <strong>Innocenzo II<\/strong>, nel XII secolo, ordin\u00f2 l&#8217;aggiunta del portico d&#8217;ingresso e di tre archi trasversali nell&#8217;interno per sostenere il duomo.<br \/>Caduta in rovina nel medioevo, fu restaurato nel XV secolo. L&#8217;anello esterno e tre braccia della croce furono distrutti. Oggi, il diametro \u00e8 di 40 metri.<\/p>\n<p>Nel XVI secolo, sotto Gregorio XIII, durante la controriforma, le pareti erano ricoperte da scene crude di martiri cristiani.<\/p>\n<h2>Descrizione<\/h2>\n<p>La chiesa \u00e8 preceduta da un portico con cinque arcate portate da antiche colonne di granito, con capitelli corinzi.<\/p>\n<div style=\"width: 210px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/frescoessantostefanorotondoroma_0892.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/frescoessantostefanorotondoroma_0892.jpg\" alt=\"santo stefano rotondo\" width=\"200\" height=\"300\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><p class=\"wp-caption-text\">Scena di martirio<\/p><\/div>\n<p>L&#8217;interno \u00e8 molto insolito. Impressionanti affreschi sulle pareti illustrano atrocit\u00e0 inflitte ai martiri cristiani. Furono realizzati nel XVI secolo da <strong>Pomarancio<\/strong> e <strong>Tempesta<\/strong>. Le 34 scene sono accompagnate da un testo che le descrive e dal nome dell&#8217;imperatore che ordin\u00f2 l&#8217;esecuzione.<\/p>\n<p>La <strong><em>cappella dei Santi Primo e Feliciano<\/em><\/strong> conserva rari mosaici del VII secolo dove sono raffigurati i due santi vestiti con mantelli da viaggio. Fu costruita da papa <strong>Teodoro I<\/strong>, che la fece erigere per depositarci le reliquie dei martiri.<\/p>\n<p>L&#8217;altare del XV secolo \u00e8 opera dell&#8217;artista fiorentino <strong>Bernardo Rossellino<\/strong>. Nell&#8217;abside, il dipinto rappresenta Cristo tra due martiri.<br \/>Il mosaico e le decorazioni in marmo risalgono al VI secolo.<\/p>\n<p>La <strong><em>cappella di Santo Stefano d&#8217;Ungheria<\/em><\/strong> fu costruita intorno al 1776 per compensare la distruzione di Santo Stefano in Vaticano, che era la chiesa nazionale degli ungheresi a Roma.<\/p>\n<p>La chiesa conserva anche l&#8217;antico trono di Papa Gregorio Magno, del VI secolo.<\/p>\n<p>Sotto la chiesa sono stati rinvenuti i resti di un <em>mitreo<\/em> (probabilmente collegato a una caserma romana) del II secolo d.C., con rilievi e affreschi, tra cui una &#8220;personificazione della luna&#8221;.<\/p>\n<h2>Galleria<\/h2>\n<p><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santastefanorotondo_0909.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/santastefanorotondo_0909.jpg\" alt=\"santo stefano rotondo\" width=\"106\" height=\"154\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santastefanorotondo_0908.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/santastefanorotondo_0908.jpg\" alt=\"santo stefano rotondo\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0898.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/santostefanorotondo_0898.jpg\" alt=\"santo stefano rotondo\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santastefanorotondorome_0901.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/santastefanorotondorome_0901.jpg\" alt=\"santo stefano rotondo\" width=\"106\" height=\"154\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santastefanorotondorome_0902.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/santastefanorotondorome_0902.jpg\" alt=\"santo stefano rotondo\" width=\"106\" height=\"154\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0883.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/santostefanorotondo_0883.jpg\" alt=\"santo stefano rotondo\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/affreschisantostefanorotondoroma_0891.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/affreschisantostefanorotondoroma_0891.jpg\" alt=\"santo stefano rotondo\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0890.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/santostefanorotondo_0890.jpg\" alt=\"santo stefano rotondo\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/frescoessantostefanorotondoroma_0891.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/frescoessantostefanorotondoroma_0891.jpg\" alt=\"santo stefano rotondo\" width=\"132\" height=\"154\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/frescoessantostefanorotondoroma_0892.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/frescoessantostefanorotondoroma_0892.jpg\" alt=\"santo stefano rotondo\" width=\"113\" height=\"154\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0885.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/santostefanorotondo_0885.jpg\" alt=\"santo stefano rotondo\" width=\"106\" height=\"154\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0887.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/santostefanorotondo_0887.jpg\" alt=\"santo stefano rotondo\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0888.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/thumbnails\/santostefanorotondo_0888.jpg\" alt=\"santo stefano rotondo\" width=\"106\" height=\"154\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><\/p>\n\n\n<h2>Vedute antiche nel arte<\/h2><div>4 opere di Chiesa Santo Stefano Rotondo sono state trovate nella database. Per vederle tutte aprire questo <a href=\"https:\/\/www.rome-roma.net\/site-rome-art.php?lieu=santo+stefano+rotondo\" target=\"_blank\">collegamento<\/a>.<\/div><div class=\"wp-block-kadence-advancedgallery kb-gallery-wrap-id-_5955fd-3f\">\r\n        <div class=\"kb-gallery-ul kb-gallery-type-fluidcarousel kb-gallery-id-_5955fd-3f kb-gallery-caption-style-below kb-gallery-magnific-init kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\">\r\n            <div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\">\r\n                <div class=\"kt-blocks-carousel-init kb-blocks-fluid-carousel kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"400\" data-slider-type=\"fluidcarousel\" data-slider-scroll=\"1\" data-slider-arrows=\"true\" data-slider-dots=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"false\" data-slider-speed=\"7000\">\r\n        <div class=\"kb-slide-item kb-gallery-carousel-item\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\">\r\n            <figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\">\r\n                <a href=\"https:\/\/www.rome-roma.net\/artmodule\/charles louis clerisseau\/charles louis clerisseau - san stefano rotondo.jpg\" class=\"kb-gallery-item-link\" style=\"color: #FFFFFF;\">\r\n                    <div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\">\r\n                        <img src=\"https:\/\/www.rome-roma.net\/artmodule\/charles louis clerisseau\/charles louis clerisseau - san stefano rotondo.jpg\" width=\"300\" height=\"200\" \r\n                            alt=\"Charles-Louis Cl\u00e9risseau,Eglise San Stefano rotondo (1740-1760, date ind\u00e9termin\u00e9e)\" \r\n                            data-full-image=\"https:\/\/www.rome-roma.net\/artmodule\/charles louis clerisseau\/charles louis clerisseau - san stefano rotondo.jpg\" \r\n                            data-light-image=\"https:\/\/www.rome-roma.net\/artmodule\/charles louis clerisseau\/charles louis clerisseau - san stefano rotondo.jpg\" data-id=\"149\" \r\n                            data-link=\"https:\/\/www.rome-roma.net\/artmodule\/charles louis clerisseau\/charles louis clerisseau - san stefano rotondo.jpg\" \r\n                            class=\"wp-image-149\" loading=lazy\/>\r\n                    <\/div><\/div>\r\n                    <figcaption class=\"kadence-blocks-gallery-item__caption\">Charles-Louis Cl\u00e9risseau, Eglise San Stefano rotondo<\/figcaption>\r\n                <\/a>\r\n            <\/figure><\/div><\/li><\/div>\r\n        <div class=\"kb-slide-item kb-gallery-carousel-item\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\">\r\n            <figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\">\r\n                <a href=\"https:\/\/www.rome-roma.net\/artmodule\/ettore roesler franz\/ettore roesler franz  - san stefano rotondo - 1888 1896.jpg\" class=\"kb-gallery-item-link\" style=\"color: #FFFFFF;\">\r\n                    <div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\">\r\n                        <img src=\"https:\/\/www.rome-roma.net\/artmodule\/ettore roesler franz\/ettore roesler franz  - san stefano rotondo - 1888 1896.jpg\" width=\"300\" height=\"200\" \r\n                            alt=\"Ettore Roesler Franz,San Stefano Rotondo (environ 1888-1896)\" \r\n                            data-full-image=\"https:\/\/www.rome-roma.net\/artmodule\/ettore roesler franz\/ettore roesler franz  - san stefano rotondo - 1888 1896.jpg\" \r\n                            data-light-image=\"https:\/\/www.rome-roma.net\/artmodule\/ettore roesler franz\/ettore roesler franz  - san stefano rotondo - 1888 1896.jpg\" data-id=\"149\" \r\n                            data-link=\"https:\/\/www.rome-roma.net\/artmodule\/ettore roesler franz\/ettore roesler franz  - san stefano rotondo - 1888 1896.jpg\" \r\n                            class=\"wp-image-149\" loading=lazy\/>\r\n                    <\/div><\/div>\r\n                    <figcaption class=\"kadence-blocks-gallery-item__caption\">Ettore Roesler Franz, San Stefano Rotondo<\/figcaption>\r\n                <\/a>\r\n            <\/figure><\/div><\/li><\/div>\r\n        <div class=\"kb-slide-item kb-gallery-carousel-item\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\">\r\n            <figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\">\r\n                <a href=\"https:\/\/www.rome-roma.net\/artmodule\/louis francois cassas\/louis francois cassas - basilica of santo stefano rotondo - rome - 1780.jpg\" class=\"kb-gallery-item-link\" style=\"color: #FFFFFF;\">\r\n                    <div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\">\r\n                        <img src=\"https:\/\/www.rome-roma.net\/artmodule\/louis francois cassas\/louis francois cassas - basilica of santo stefano rotondo - rome - 1780.jpg\" width=\"300\" height=\"200\" \r\n                            alt=\"Louis-Fran\u00e7ois Cassas,Basilique de Santo Stefano Rotondo (environ 1780)\" \r\n                            data-full-image=\"https:\/\/www.rome-roma.net\/artmodule\/louis francois cassas\/louis francois cassas - basilica of santo stefano rotondo - rome - 1780.jpg\" \r\n                            data-light-image=\"https:\/\/www.rome-roma.net\/artmodule\/louis francois cassas\/louis francois cassas - basilica of santo stefano rotondo - rome - 1780.jpg\" data-id=\"149\" \r\n                            data-link=\"https:\/\/www.rome-roma.net\/artmodule\/louis francois cassas\/louis francois cassas - basilica of santo stefano rotondo - rome - 1780.jpg\" \r\n                            class=\"wp-image-149\" loading=lazy\/>\r\n                    <\/div><\/div>\r\n                    <figcaption class=\"kadence-blocks-gallery-item__caption\">Louis-Fran\u00e7ois Cassas, Basilique de Santo Stefano Rotondo<\/figcaption>\r\n                <\/a>\r\n            <\/figure><\/div><\/li><\/div>\r\n        <div class=\"kb-slide-item kb-gallery-carousel-item\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\">\r\n            <figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\">\r\n                <a href=\"https:\/\/www.rome-roma.net\/artmodule\/nicolle victor jean\/nicolle victor jean - vue de la cour - du portique et de l entree de l eglise saint etienne-le-rond.jpg\" class=\"kb-gallery-item-link\" style=\"color: #FFFFFF;\">\r\n                    <div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain\">\r\n                        <img src=\"https:\/\/www.rome-roma.net\/artmodule\/nicolle victor jean\/nicolle victor jean - vue de la cour - du portique et de l entree de l eglise saint etienne-le-rond.jpg\" width=\"300\" height=\"200\" \r\n                            alt=\"Victor-Jean Nicolle,Vue de la cour et du portique de Santo Stefano Rotondo (?, avant 1826, date ind\u00e9termin\u00e9e)\" \r\n                            data-full-image=\"https:\/\/www.rome-roma.net\/artmodule\/nicolle victor jean\/nicolle victor jean - vue de la cour - du portique et de l entree de l eglise saint etienne-le-rond.jpg\" \r\n                            data-light-image=\"https:\/\/www.rome-roma.net\/artmodule\/nicolle victor jean\/nicolle victor jean - vue de la cour - du portique et de l entree de l eglise saint etienne-le-rond.jpg\" data-id=\"149\" \r\n                            data-link=\"https:\/\/www.rome-roma.net\/artmodule\/nicolle victor jean\/nicolle victor jean - vue de la cour - du portique et de l entree de l eglise saint etienne-le-rond.jpg\" \r\n                            class=\"wp-image-149\" loading=lazy\/>\r\n                    <\/div><\/div>\r\n                    <figcaption class=\"kadence-blocks-gallery-item__caption\">Victor-Jean Nicolle, Vue de la cour et du portique de Santo Stefano Rotondo<\/a> (\u0152uvre pr\u00e9sente \u00e0 la <a href=\"https:\/\/galerievittet.com\/\" target=\"_blank\">Galerie Claude Vittet<\/a>)<a><\/figcaption>\r\n                <\/a>\r\n            <\/figure><\/div><\/li><\/div><\/div><\/div><\/div><\/div><a href=\"https:\/\/www.rome-roma.net\/site-rome-art.php?lieu=santo+stefano+rotondo\" target=\"_blank\">Clica per vedere oltre dipinti e artisti su Santo Stefano Rotondo in Roma<\/a><br><br>\n\n\n\n<h2>Cartina ed indirizzo<\/h2>\r\n\t\t<b>Indirizzo : <\/b>Via Santo Stefano Rotondo, 7, 00184 Roma RM, Italie<div id=\"travelersmap-container-6a0403552aea3\" class=\"travelersmap-container\" style=\"z-index: 1; min-height: 10px; min-width:10px; height:400px;width:100%; max-width:; max-height:; position:relative;\"><div style=\"position:absolute; z-index:-1;top: 50%;text-align: center;display: block;left: 50%;transform: translate(-50%,-50%);\">Travelers' Map is loading... <br> If you see this after your page is loaded completely, leafletJS files are missing.<\/div><\/div><i>Clicca sulla freccia per localizzarti sulla mappa<\/i><br><br>\n\n\n\n<h2>Informazioni<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr style=\"background-color: #fae8c3;\">\n<td style=\"width: 100%;\"><span style=\"font-size: 10pt;\"><strong>Chiesa Santa Stefano Rotondo al Celio<\/strong><\/span><br \/><span style=\"font-size: 10pt;\"><em>Via di Santo Stefano Rotondo, 7<\/em><\/span><\/td>\n<\/tr>\n<tr style=\"background-color: #f7ece1;\">\n<td style=\"width: 100%;\">\n<p><span style=\"font-size: 10pt;\"><strong>Orari<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 10pt;\">Dall&#8217;ultima domenica di ottobre al sabato prima dell&#8217;ultima domenica di marzo:<br \/>Dal marted\u00ec alla domenica: 10.00 &#8211; 13.00 \/ 14.00 &#8211; 17.00<\/span><\/li>\n<li><span style=\"font-size: 10pt;\">Dall&#8217;ultima domenica di marzo al sabato prima dell&#8217;ultima domenica di ottobre:<br \/>Dal marted\u00ec alla domenica: 10.00 &#8211; 13.00 \/ 15.30 &#8211; 18.30<\/span><\/li>\n<li><span style=\"font-size: 10pt;\">Luned\u00ec: chiuso<\/span><\/li>\n<li><span style=\"font-size: 10pt;\">Chiuso il 25 dicembre, 1 gennaio e domenica di Pasqua. Chiuso tre settimane in agosto (dalla settimana precedente ferragosto alla settimana successiva), e dal 7 al 21 gennaio.<\/span><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr style=\"background-color: #fae8c3;\">\n<td style=\"width: 100%;\">\n<p><span style=\"font-size: 10pt;\"><strong>Fonti e collegamenti<br \/><\/strong><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 10pt;\">Sito ufficiale : <a href=\"https:\/\/www.cgu.it\/it\/santo-stefano-rotondo\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.cgu.it\/it\/santo-stefano-rotondo<\/a><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><a href=\"https:\/\/060608.comune.roma.it\/turismo-religioso\/chiese-cattoliche\/chiesa-di-santo-stefano-rotondo-al-celio-13441\" target=\"_blank\" rel=\"noopener\">Sito del comune 060608<\/a><br \/><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><a href=\"https:\/\/it.wikipedia.org\/wiki\/Basilica_di_Santo_Stefano_Rotondo_al_Celio\" target=\"_blank\" rel=\"noopener noreferrer\">Pagina Wikipedia<\/a><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><a href=\"https:\/\/www.romasegreta.it\/monti\/s-stefano-rotondo.html\" target=\"_blank\" rel=\"noopener noreferrer\">Pagina su Roma Segreta<\/a><br \/><\/span><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\n\n<h3>Articoli Colle Celio<\/h3>\n\n\n\n<ul class=\"lcp_catlist\" id=\"lcp_instance_0\"><li><a href=\"https:\/\/www.rome-roma.net\/it\/basilica-dei-santi-quattro-coronati\/\">Basilica dei Santi Quattro Coronati<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/basilica-dei-santi-quattro-coronati\/\" title=\"Basilica dei Santi Quattro Coronati\"><img width=\"50\" height=\"50\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/chiesasantiquattrocoronati_09521-150x150.jpg\" class=\"classthumblist wp-post-image\" alt=\"Basilica dei Santi Quattro Coronati\" loading=\"lazy\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/chiesasantiquattrocoronati_09521-150x150.jpg 150w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/chiesasantiquattrocoronati_09521-50x50.jpg 50w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/chiesasantiquattrocoronati_09521-80x80.jpg 80w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/chiesasantiquattrocoronati_09521-75x75.jpg 75w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><div class=\"lcp_excerpt\">A nord del Colle Celio a Roma, la Basilica dei Quattro Coronati ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/basilica-dei-santi-giovanni-e-paolo\/\">Basilica dei Santi Giovanni e Paolo<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/basilica-dei-santi-giovanni-e-paolo\/\" title=\"Basilica dei Santi Giovanni e Paolo\"><img src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/campanile-basilica-santi-giovanni-e-paolo-roma_0919-200x300.jpg\" class=\"classthumblist\"  alt=\"Basilica dei Santi Giovanni e Paolo\" \/><\/a><div class=\"lcp_excerpt\">Sul colle Celio a Roma, la basilica dei Santi Giovanni e Paolo ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/case-romane-del-celio\/\">Case Romane del Celio<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/case-romane-del-celio\/\" title=\"Case Romane del Celio\"><img width=\"50\" height=\"50\" src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2022\/07\/casa-romana-al-celio-150x150.jpg\" class=\"classthumblist wp-post-image\" alt=\"Case Romane del Celio\" loading=\"lazy\" srcset=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2022\/07\/casa-romana-al-celio-150x150.jpg 150w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2022\/07\/casa-romana-al-celio-50x50.jpg 50w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2022\/07\/casa-romana-al-celio-80x80.jpg 80w, https:\/\/www.rome-roma.net\/wp-content\/uploads\/2022\/07\/casa-romana-al-celio-75x75.jpg 75w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><div class=\"lcp_excerpt\">\nSulla collina del Celio, la grande chiesa di San Giovanni e Paolo, ...<\/div><\/li><li class=\"current\"><a href=\"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/\">Chiesa Santo Stefano Rotondo<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/\" title=\"Chiesa Santo Stefano Rotondo\"><img src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0898.jpg\" class=\"classthumblist\"  alt=\"Chiesa Santo Stefano Rotondo\" \/><\/a><div class=\"lcp_excerpt\">Sul colle Celio, la chiesa di Santo Stefano Rotondo, costruita nel V ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/colle-celio\/visita-del-colle-celio\/\">Visita del colle Celio<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/colle-celio\/visita-del-colle-celio\/\" title=\"Visita del colle Celio\"><img src=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/villacelimontana_0938.jpg\" class=\"classthumblist\"  alt=\"Visita del colle Celio\" \/><\/a><div class=\"lcp_excerpt\">Situata ad est del colle Palatino, il colle Celio \u00e8 una delle ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/villa-celimontana-parco\/\">Parco della Villa Celimontana<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/villa-celimontana-parco\/\" title=\"Parco della Villa Celimontana\"><img src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/villa-celimontana_0936-300x200.jpg\" class=\"classthumblist\"  alt=\"Parco della Villa Celimontana\" \/><\/a><div class=\"lcp_excerpt\">La Villa Celimontana \u00e8 un parco storico unico, situato sul\u00a0 Colle Celio ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/santa-maria-in-domnica-alla-navicella\/\">Chiesa di Santa Maria in Domnica alla Navicella<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/santa-maria-in-domnica-alla-navicella\/\" title=\"Chiesa di Santa Maria in Domnica alla Navicella\"><img src=\"https:\/\/www.rome-roma.net\/photos\/voyage2\/roma\/images\/roma_santamariaindomnicab_9803.jpg\" class=\"classthumblist\"  alt=\"Chiesa di Santa Maria in Domnica alla Navicella\" \/><\/a><div class=\"lcp_excerpt\">La chiesa di Santa Maria in Domnica, o alla Navicella, fu fondata ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/chiesa-san-gregorio-al-celio\/\">Chiesa San Gregorio al Celio<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/chiesa-san-gregorio-al-celio\/\" title=\"Chiesa San Gregorio al Celio\"><img src=\"https:\/\/www.rome-roma.net\/photos\/eglises\/san%20gregorio%20al%20celio\/images\/san_gregorio_al_celio_roma_8597.jpg\" class=\"classthumblist\"  alt=\"Chiesa San Gregorio al Celio\" \/><\/a><div class=\"lcp_excerpt\">Di origine medievale, la chiesa fu trasformata nel XVII e XVIII secolo.\u00c8 ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/storia-colle-celio\/\">Storia del colle Celio<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/storia-colle-celio\/\" title=\"Storia del colle Celio\"><img src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/02\/collines-de-rome-150x150.jpg\" class=\"classthumblist\"  alt=\"Storia del colle Celio\" \/><\/a><div class=\"lcp_excerpt\">Il Celio \u00e8 oggi il nome di uno dei Rioni di Roma, ...<\/div><\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sul colle Celio, la chiesa di Santo Stefano Rotondo, costruita nel V secolo, \u00e8 una delle chiese circolari pi\u00f9 antiche d&#8217;Italia, la prima in Roma.Fu consacrata a San Stefano alla fine del V secolo. Il piano originale comprendeva due colonnati concentrici, delimitando due ambulacri concentrici, con un diametro totale di 65 metri, che tagliavano le [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"kt_blocks_editor_width":"","_links_to":"","_links_to_target":""},"genre":[270],"interet":[287],"quartier":[312,313],"categorie_site":[382],"quartier_historique":[449],"etiquettes_site":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chiesa Santo Stefano Rotondo &ndash; Rome-Roma<\/title>\n<meta name=\"description\" content=\"Sul colle Celio di Roma, questa antica chiesa circolare fu costruita nel V secolo. Affreschi crudi e insoliti di martiri cristiani adornano le sue pareti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiesa Santo Stefano Rotondo &ndash; Rome-Roma\" \/>\n<meta property=\"og:description\" content=\"Sul colle Celio di Roma, questa antica chiesa circolare fu costruita nel V secolo. Affreschi crudi e insoliti di martiri cristiani adornano le sue pareti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rome-Roma\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-13T20:49:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0898.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/#organization\",\"name\":\"Rome-Roma\",\"url\":\"https:\/\/www.rome-roma.net\/it\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg\",\"contentUrl\":\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg\",\"width\":420,\"height\":420,\"caption\":\"Rome-Roma\"},\"image\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/#website\",\"url\":\"https:\/\/www.rome-roma.net\/it\/\",\"name\":\"Rome-Roma\",\"description\":\"Cultura & Viaggio\",\"publisher\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rome-roma.net\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0898.jpg\",\"contentUrl\":\"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0898.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/#webpage\",\"url\":\"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/\",\"name\":\"Chiesa Santo Stefano Rotondo &ndash; Rome-Roma\",\"isPartOf\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/#primaryimage\"},\"datePublished\":\"2020-01-20T15:46:23+00:00\",\"dateModified\":\"2024-12-13T20:49:06+00:00\",\"description\":\"Sul colle Celio di Roma, questa antica chiesa circolare fu costruita nel V secolo. Affreschi crudi e insoliti di martiri cristiani adornano le sue pareti.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.rome-roma.net\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiesa Santo Stefano Rotondo\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiesa Santo Stefano Rotondo &ndash; Rome-Roma","description":"Sul colle Celio di Roma, questa antica chiesa circolare fu costruita nel V secolo. Affreschi crudi e insoliti di martiri cristiani adornano le sue pareti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/","og_locale":"it_IT","og_type":"article","og_title":"Chiesa Santo Stefano Rotondo &ndash; Rome-Roma","og_description":"Sul colle Celio di Roma, questa antica chiesa circolare fu costruita nel V secolo. Affreschi crudi e insoliti di martiri cristiani adornano le sue pareti.","og_url":"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/","og_site_name":"Rome-Roma","article_modified_time":"2024-12-13T20:49:06+00:00","og_image":[{"url":"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0898.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.rome-roma.net\/it\/#organization","name":"Rome-Roma","url":"https:\/\/www.rome-roma.net\/it\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.rome-roma.net\/it\/#logo","inLanguage":"it-IT","url":"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg","contentUrl":"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg","width":420,"height":420,"caption":"Rome-Roma"},"image":{"@id":"https:\/\/www.rome-roma.net\/it\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.rome-roma.net\/it\/#website","url":"https:\/\/www.rome-roma.net\/it\/","name":"Rome-Roma","description":"Cultura & Viaggio","publisher":{"@id":"https:\/\/www.rome-roma.net\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rome-roma.net\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0898.jpg","contentUrl":"https:\/\/www.rome-roma.net\/photos\/stefanoRotondo-QuattroSanti-PaoloeGiovanni\/images\/santostefanorotondo_0898.jpg"},{"@type":"WebPage","@id":"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/#webpage","url":"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/","name":"Chiesa Santo Stefano Rotondo &ndash; Rome-Roma","isPartOf":{"@id":"https:\/\/www.rome-roma.net\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/#primaryimage"},"datePublished":"2020-01-20T15:46:23+00:00","dateModified":"2024-12-13T20:49:06+00:00","description":"Sul colle Celio di Roma, questa antica chiesa circolare fu costruita nel V secolo. Affreschi crudi e insoliti di martiri cristiani adornano le sue pareti.","breadcrumb":{"@id":"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rome-roma.net\/it\/chiesa-santo-stefano-rotondo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.rome-roma.net\/it\/"},{"@type":"ListItem","position":2,"name":"Chiesa Santo Stefano Rotondo"}]}]}},"acf_fields":{"nom_monument":null,"wikidata":"Q919456","sameas":null},"_links":{"self":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/site\/7549"}],"collection":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/site"}],"about":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/types\/site"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/comments?post=7549"}],"wp:attachment":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/media?parent=7549"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/genre?post=7549"},{"taxonomy":"interet","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/interet?post=7549"},{"taxonomy":"quartier","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/quartier?post=7549"},{"taxonomy":"categorie_site","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/categorie_site?post=7549"},{"taxonomy":"quartier_historique","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/quartier_historique?post=7549"},{"taxonomy":"etiquettes_site","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/etiquettes_site?post=7549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}