


{"id":8061,"date":"2020-02-10T15:31:46","date_gmt":"2020-02-10T14:31:46","guid":{"rendered":"https:\/\/www.rome-roma.net\/site\/fontaine-des-naiades\/"},"modified":"2025-01-02T13:16:26","modified_gmt":"2025-01-02T12:16:26","slug":"fontana-delle-naiadi","status":"publish","type":"site","link":"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/","title":{"rendered":"Fontana delle Naiadi"},"content":{"rendered":"<div style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5623.jpg\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5623.jpg\" alt=\"Fontaine des Na\u00efades\" width=\"300\" height=\"200\" border=\"0\" hspace=\"4\" vspace=\"4\" \/><\/a><p class=\"wp-caption-text\">Fontana delle Naiadi<\/p><\/div>\n<p>Con le sue allegre naiadi in bronzo, la <strong>Fontana delle Naiadi<\/strong> \u00e8 la pi\u00f9 bella delle fontane moderne di Roma, in <a href=\"https:\/\/www.rome-roma.net\/it\/piazza-della-repubblica\/\"><strong>Piazza della Repubblica<\/strong><\/a>.<\/p>\n<h2>Origine della fontana<\/h2>\n<p>La vecchia <strong>fontana dell\u2019Acqua Marcia<\/strong>, rinominata Fontana Pia in onore di Papa Pio IX, fu inaugurata nel 1870 vicino all\u2019attuale <a href=\"https:\/\/www.rome-roma.net\/it\/obelisco-di-dogali\/\">monumento di Dogali<\/a>. Come l\u2019attuale fontana, era alimentata dalla sorgente Marcia, una delle pi\u00f9 celebri di Roma.<\/p>\n<p>Durante la ristrutturazione del quartiere della stazione Termini, fu spostata in Piazza dell&#8217;Esedra (l\u2019attuale <a href=\"https:\/\/www.rome-roma.net\/it\/piazza-della-repubblica\/\">Piazza Repubblica<\/a>), ricostruita nel 1888 al centro del grande esedra delle <a href=\"https:\/\/www.rome-roma.net\/it\/terme-di-diocleziano\/\">Terme di Diocleziano<\/a> su progetto di <strong>Alessandro Guerrieri<\/strong>, in cima alla Via Nazionale.<\/p>\n<p>Nel 1901, il bacino circolare fu decorato con i quattro gruppi in bronzo delle naiadi nude dello scultore palermitano <strong>Mario Rutelli<\/strong>. Queste figure femminili con forme generose, adagiate su animali e creature marine, suscitano una controversia al loro apparire, giudicate provocanti, e rimasero nascoste dietro una recinzione di legno a causa delle dispute al riguardo. <br \/>Completato nel 1911, il gruppo centrale di Rutelli, con tritoni, un delfino e un polpo, non piacque e fu spostato nel parco di <a href=\"https:\/\/www.rome-roma.net\/it\/piazza-vittorio-emanuele-ii-ninfeo-alessandro\/\">Piazza Vittorio Emanuele II<\/a>. Nel 1913, fu sostituito dalla scultura attuale che rappresenta il dio Glauco, aggrappato a un delfino da cui l\u2019acqua scaturisce dalla bocca. Quest\u2019opera, segnata dallo <strong>Art Nouveau<\/strong>, illustra il dominio dell\u2019uomo sulle forze della natura.<\/p>\n<p>Inaugurata definitivamente nel <strong>1914<\/strong>, la Fontana delle Naiadi \u00e8 la pi\u00f9 significativa dell\u2019arte in stile liberty della citt\u00e0.<\/p>\n<p>Le naiadi di Rutelli incarnano ciascuna un elemento acquatico: la Ninfa del lago con il suo cigno; la Ninfa del fiume, distesa su un mostro serpentino fluviale; la Ninfa dell\u2019oceano, a cavallo di un cavallo simbolo del mare; e la Ninfa delle acque sotterranee, adagiata su un misterioso lucertolone.<\/p>\n<h2>Galleria<\/h2>\n<p style=\"text-align: left;\" align=\"center\"><span class=\"desc\"><a href=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5622.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/thumbnails\/piazzarepubblica_5622.jpg\" alt=\"place de la r\u00e9publique\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5623.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/thumbnails\/piazzarepubblica_5623.jpg\" alt=\"place de la r\u00e9publique\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><\/span><span class=\"desc\"><a href=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5624.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/thumbnails\/piazzarepubblica_5624.jpg\" alt=\"place de la r\u00e9publique\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><\/span><span class=\"desc\"><a href=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5625.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/thumbnails\/piazzarepubblica_5625.jpg\" alt=\"place de la r\u00e9publique\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><br \/><\/span><span class=\"desc\"><a href=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5627.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/thumbnails\/piazzarepubblica_5627.jpg\" alt=\"place de la r\u00e9publique\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><\/span><span class=\"desc\"><a href=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/placedelarepublique_rome_5620.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/thumbnails\/placedelarepublique_rome_5620.jpg\" alt=\"place de la r\u00e9publique\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><\/span><span class=\"desc\"><a href=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/placedelarepublique_rome_5635.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/thumbnails\/placedelarepublique_rome_5635.jpg\" alt=\"place de la r\u00e9publique\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><a href=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/placedelarepublique_rome_5639.jpg\" rel=\"lightbox[a]\"><img loading=\"lazy\" src=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/thumbnails\/placedelarepublique_rome_5639.jpg\" alt=\"place de la r\u00e9publique\" width=\"154\" height=\"106\" border=\"0\" hspace=\"3\" vspace=\"3\" \/><\/a><\/span><\/p>\n\n\n<h2>Cartina ed indirizzo<\/h2>\r\n\t\t<b>Indirizzo : <\/b>Piazza della Repubblica, 00185 Roma RM, Italie<div id=\"travelersmap-container-6a04da652eddc\" class=\"travelersmap-container\" style=\"z-index: 1; min-height: 10px; min-width:10px; height:400px;width:100%; max-width:; max-height:; position:relative;\"><div style=\"position:absolute; z-index:-1;top: 50%;text-align: center;display: block;left: 50%;transform: translate(-50%,-50%);\">Travelers' Map is loading... <br> If you see this after your page is loaded completely, leafletJS files are missing.<\/div><\/div><i>Clicca sulla freccia per localizzarti sulla mappa<\/i><br><br>\n\n\n\n<h2>Sulla piazza della Repubblica<\/h2>\n\n\n\n<ul class=\"lcp_catlist\" id=\"lcp_instance_0\"><li><a href=\"https:\/\/www.rome-roma.net\/it\/piazza-della-repubblica\/\">Piazza della Repubblica<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/piazza-della-repubblica\/\" title=\"Piazza della Repubblica\"><img src=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/placedelarepublique_rome_5639.jpg\" class=\"classthumblist\"  alt=\"Piazza della Repubblica\" \/><\/a><div class=\"lcp_excerpt\">La Piazza della Repubblica \u00e8 una piazza famosa di Roma, situata a poche centinaia di metri dalla stazione Termini, di fronte ai resti delle Terme ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/basilica-santa-maria-degli-angeli\/\">Basilica Santa Maria degli Angeli<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/basilica-santa-maria-degli-angeli\/\" title=\"Basilica Santa Maria degli Angeli\"><img src=\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2020\/01\/transept-basilique-sainte-marie-des-anges-rome-roma_0456-300x200.jpg\" class=\"classthumblist\"  alt=\"Basilica Santa Maria degli Angeli\" \/><\/a><div class=\"lcp_excerpt\">La Basilica di Santa Maria degli Angeli a Roma fu costruita nel XVI secolo in una parte delle antiche terme di Diocleziano. Visita, orari e ...<\/div><\/li><li class=\"current\"><a href=\"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/\">Fontana delle Naiadi<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/\" title=\"Fontana delle Naiadi\"><img src=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5623.jpg\" class=\"classthumblist\"  alt=\"Fontana delle Naiadi\" \/><\/a><div class=\"lcp_excerpt\">Con le sue allegre naiadi in bronzo, la Fontana delle Naiadi \u00e8 la pi\u00f9 bella delle fontane moderne di Roma, in Piazza della Repubblica.\nOrigine della ...<\/div><\/li><li><a href=\"https:\/\/www.rome-roma.net\/it\/obelisco-di-dogali\/\">Obelisco di Dogali e Monumento ai caduti<\/a><a href=\"https:\/\/www.rome-roma.net\/it\/obelisco-di-dogali\/\" title=\"Obelisco di Dogali e Monumento ai caduti\"><img src=\"https:\/\/www.rome-roma.net\/foto\/sitimonumenti\/images\/obelisco_di_dogali_0819.jpg\" class=\"classthumblist\"  alt=\"Obelisco di Dogali e Monumento ai caduti\" \/><\/a><div class=\"lcp_excerpt\">L&#8217;obelisco di Dogali \u00e8 uno dei tredici obelischi antichi di Roma. Si trova in Viale Luigi Einaudi, vicino alle Terme di Diocleziano, a Piazza della ...<\/div><\/li><\/ul>\n\n\n<p><!--EndFragment--><\/p>\n<h2>Informazioni<\/h2>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr style=\"background-color: #fae8c3;\">\n<td style=\"width: 100%;\"><span style=\"font-size: 10pt;\"><strong>Fontana delle Naiadi<\/strong><\/span><br \/><span style=\"font-size: 10pt;\"><em>Piazza della Repubblica, 00185 Roma<\/em><\/span><\/td>\n<\/tr>\n<tr style=\"background-color: #f7ece1;\">\n<td style=\"width: 100%;\">\n<p><span style=\"font-size: 10pt;\"><b>Fonti e collegamenti<\/b><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 10pt;\">Web siti della citt\u00e0 di Roma : <a href=\"https:\/\/www.turismoroma.it\/it\/node\/1284\" target=\"_blank\" rel=\"noopener\">Fontana delle Naiadi su 060608<\/a>, <a href=\"https:\/\/www.sovraintendenzaroma.it\/i_luoghi\/roma_medioevale_e_moderna\/fontane\/fontana_delle_najadi_mostra_del_nuovo_acquedotto_marcio\" target=\"_blank\" rel=\"noopener\">www.sovraintendenzaroma.it<\/a><\/span><\/li>\n<li><span style=\"font-size: 10pt;\"><a href=\"https:\/\/it.wikipedia.org\/wiki\/Fontana_delle_Naiadi\" target=\"_blank\" rel=\"noopener noreferrer\">Fontana delle Naiadi su Wikipedia<\/a><\/span><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Con le sue allegre naiadi in bronzo, la Fontana delle Naiadi \u00e8 la pi\u00f9 bella delle fontane moderne di Roma, in Piazza della Repubblica. Origine della fontana La vecchia fontana dell\u2019Acqua Marcia, rinominata Fontana Pia in onore di Papa Pio IX, fu inaugurata nel 1870 vicino all\u2019attuale monumento di Dogali. Come l\u2019attuale fontana, era alimentata [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"kt_blocks_editor_width":"","_links_to":"","_links_to_target":""},"genre":[271],"interet":[286],"quartier":[339,320],"categorie_site":[387,399],"quartier_historique":[444],"etiquettes_site":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fontana delle Naiadi &ndash; Rome-Roma<\/title>\n<meta name=\"description\" content=\"Al centro della Piazza della Repubblica a Roma si trova la Fontana delle Naiadi, opera di Guerrieri e Rutelli (1901), che sostituisce la Fontana Pia, con quattro naiadi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fontana delle Naiadi &ndash; Rome-Roma\" \/>\n<meta property=\"og:description\" content=\"Al centro della Piazza della Repubblica a Roma si trova la Fontana delle Naiadi, opera di Guerrieri e Rutelli (1901), che sostituisce la Fontana Pia, con quattro naiadi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rome-Roma\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-02T12:16:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5623.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/#organization\",\"name\":\"Rome-Roma\",\"url\":\"https:\/\/www.rome-roma.net\/it\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg\",\"contentUrl\":\"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg\",\"width\":420,\"height\":420,\"caption\":\"Rome-Roma\"},\"image\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/#website\",\"url\":\"https:\/\/www.rome-roma.net\/it\/\",\"name\":\"Rome-Roma\",\"description\":\"Cultura & Viaggio\",\"publisher\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rome-roma.net\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5623.jpg\",\"contentUrl\":\"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5623.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/#webpage\",\"url\":\"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/\",\"name\":\"Fontana delle Naiadi &ndash; Rome-Roma\",\"isPartOf\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/#primaryimage\"},\"datePublished\":\"2020-02-10T14:31:46+00:00\",\"dateModified\":\"2025-01-02T12:16:26+00:00\",\"description\":\"Al centro della Piazza della Repubblica a Roma si trova la Fontana delle Naiadi, opera di Guerrieri e Rutelli (1901), che sostituisce la Fontana Pia, con quattro naiadi\",\"breadcrumb\":{\"@id\":\"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.rome-roma.net\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fontana delle Naiadi\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fontana delle Naiadi &ndash; Rome-Roma","description":"Al centro della Piazza della Repubblica a Roma si trova la Fontana delle Naiadi, opera di Guerrieri e Rutelli (1901), che sostituisce la Fontana Pia, con quattro naiadi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/","og_locale":"it_IT","og_type":"article","og_title":"Fontana delle Naiadi &ndash; Rome-Roma","og_description":"Al centro della Piazza della Repubblica a Roma si trova la Fontana delle Naiadi, opera di Guerrieri e Rutelli (1901), che sostituisce la Fontana Pia, con quattro naiadi","og_url":"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/","og_site_name":"Rome-Roma","article_modified_time":"2025-01-02T12:16:26+00:00","og_image":[{"url":"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5623.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.rome-roma.net\/it\/#organization","name":"Rome-Roma","url":"https:\/\/www.rome-roma.net\/it\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.rome-roma.net\/it\/#logo","inLanguage":"it-IT","url":"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg","contentUrl":"https:\/\/www.rome-roma.net\/wp-content\/uploads\/2025\/07\/logo-rome-roma-420.jpg","width":420,"height":420,"caption":"Rome-Roma"},"image":{"@id":"https:\/\/www.rome-roma.net\/it\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.rome-roma.net\/it\/#website","url":"https:\/\/www.rome-roma.net\/it\/","name":"Rome-Roma","description":"Cultura & Viaggio","publisher":{"@id":"https:\/\/www.rome-roma.net\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rome-roma.net\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5623.jpg","contentUrl":"https:\/\/www.rome-roma.net\/photos\/visite-rome\/images\/piazzarepubblica_5623.jpg"},{"@type":"WebPage","@id":"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/#webpage","url":"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/","name":"Fontana delle Naiadi &ndash; Rome-Roma","isPartOf":{"@id":"https:\/\/www.rome-roma.net\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/#primaryimage"},"datePublished":"2020-02-10T14:31:46+00:00","dateModified":"2025-01-02T12:16:26+00:00","description":"Al centro della Piazza della Repubblica a Roma si trova la Fontana delle Naiadi, opera di Guerrieri e Rutelli (1901), che sostituisce la Fontana Pia, con quattro naiadi","breadcrumb":{"@id":"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rome-roma.net\/it\/fontana-delle-naiadi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.rome-roma.net\/it\/"},{"@type":"ListItem","position":2,"name":"Fontana delle Naiadi"}]}]}},"acf_fields":{"nom_monument":null,"wikidata":"Q7489878","sameas":null},"_links":{"self":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/site\/8061"}],"collection":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/site"}],"about":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/types\/site"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/comments?post=8061"}],"wp:attachment":[{"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/media?parent=8061"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/genre?post=8061"},{"taxonomy":"interet","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/interet?post=8061"},{"taxonomy":"quartier","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/quartier?post=8061"},{"taxonomy":"categorie_site","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/categorie_site?post=8061"},{"taxonomy":"quartier_historique","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/quartier_historique?post=8061"},{"taxonomy":"etiquettes_site","embeddable":true,"href":"https:\/\/www.rome-roma.net\/it\/wp-json\/wp\/v2\/etiquettes_site?post=8061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}